{"id":4474,"date":"2022-08-15T16:38:39","date_gmt":"2022-08-15T14:38:39","guid":{"rendered":"https:\/\/www.edilonsedra.com\/?post_type=discover&#038;p=4474"},"modified":"2023-10-05T10:36:05","modified_gmt":"2023-10-05T08:36:05","slug":"isolation-electrique","status":"publish","type":"discover","link":"https:\/\/www.edilonsedra.com\/fr\/discover\/isolation-electrique\/","title":{"rendered":"Isolation \u00e9lectrique"},"content":{"rendered":"\n<h4 class=\"wp-block-heading\">Comment contr\u00f4ler les dommages caus\u00e9s par les courants vagabonds<\/h4>\n\n\n\n<p><\/p>\n\n\n\n<p>Les courants vagabonds sont une cons\u00e9quence n\u00e9faste des syst\u00e8mes ferroviaires \u00e9lectrifi\u00e9s, qui provoquent ou acc\u00e9l\u00e8rent la corrosion \u00e9lectrolytique des rails et des structures m\u00e9talliques environnantes, ce qui peut entra\u00eener des situations dangereuses.<\/p>\n\n\n\n<p>Les syst\u00e8mes de fixation des rails d&rsquo;edilon)(sedra sont con\u00e7us pour une isolation optimale des rails et offrent un degr\u00e9 impressionnant de r\u00e9duction des courants vagabonds. Regardez la vid\u00e9o d&rsquo;animation ci-dessous pour apprendre comment pr\u00e9venir les dommages caus\u00e9s par les courants vagabonds.<\/p>\n\n\n\n<div class=\"cookieconsent-optout-marketing\">\n  <em>Please <a href=\"javascript: Cookiebot.renew()\">accept marketing cookies<\/a>\n  to view this video.<\/em>\n<\/div>\n<div class=\"cookieconsent-optin-marketing\">\n<div class=\"responsive-embed widescreen\">\n<iframe loading=\"lazy\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/Q-r4p8PoI9g\" title=\"How to prevent stray current damage to LRT track &amp; infrastructure? System solution: Corkelast\u00ae ERS\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen=\"\" width=\"560\" height=\"315\" frameborder=\"0\"><\/iframe><\/div><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Transport Canberra choisit edilon)(sedra<\/h3>\n\n\n\n<p>L&rsquo;isolation \u00e9lectrique est un argument important pour de nombreux exploitants ferroviaires qui choisissent les syst\u00e8mes de fixation des rails d&rsquo;edilon)(sedra. Transport Canberra en Australie en est un bon exemple.<\/p>\n\n\n\n<p>Un groupe de travail australien de Canberra Metro a \u00e9tudi\u00e9 l&rsquo;isolation \u00e9lectrique de notre syst\u00e8me de fixation des rails Corkelast\u00ae ERS install\u00e9 \u00e0 Canberra. Les valeurs de r\u00e9sistance rail-terre mesur\u00e9es dans des conditions humides d\u00e9passent 20 ohms\u00b7km, tandis que des conditions s\u00e8ches montrent des valeurs ph\u00e9nom\u00e9nales de 60 \u00e0 80 ohms\u00b7km. edilon)(sedra Australia a install\u00e9 au total 12 km de syst\u00e8me edilon)(sedra Corkelast\u00ae ERS (Embedded Rail System) hautement isolant \u00e0 Canberra.<\/p>\n\n\n\n<p>Vous souhaitez en savoir plus sur cette recherche ? Ou avez-vous des questions sur l&rsquo;isolation \u00e9lectrique des voies ? N&rsquo;h\u00e9sitez pas \u00e0 poser vos questions \u00e0 l&rsquo;un de nos experts!<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"769\" src=\"https:\/\/www.edilonsedra.com\/wp-content\/uploads\/2022\/08\/Corkelast-ERS-Canberra-Light-Rail-1024x769.jpg\" alt=\"\" class=\"wp-image-2624\" srcset=\"https:\/\/www.edilonsedra.com\/wp-content\/uploads\/2022\/08\/Corkelast-ERS-Canberra-Light-Rail-1024x769.jpg 1024w, https:\/\/www.edilonsedra.com\/wp-content\/uploads\/2022\/08\/Corkelast-ERS-Canberra-Light-Rail-300x225.jpg 300w, https:\/\/www.edilonsedra.com\/wp-content\/uploads\/2022\/08\/Corkelast-ERS-Canberra-Light-Rail-768x576.jpg 768w, https:\/\/www.edilonsedra.com\/wp-content\/uploads\/2022\/08\/Corkelast-ERS-Canberra-Light-Rail-1536x1153.jpg 1536w, https:\/\/www.edilonsedra.com\/wp-content\/uploads\/2022\/08\/Corkelast-ERS-Canberra-Light-Rail-200x150.jpg 200w, https:\/\/www.edilonsedra.com\/wp-content\/uploads\/2022\/08\/Corkelast-ERS-Canberra-Light-Rail.jpg 2000w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Comment contr\u00f4ler les dommages caus\u00e9s par les courants vagabonds Les courants vagabonds sont une cons\u00e9quence n\u00e9faste des syst\u00e8mes ferroviaires \u00e9lectrifi\u00e9s, qui provoquent ou acc\u00e9l\u00e8rent la corrosion \u00e9lectrolytique des rails et des structures m\u00e9talliques environnantes, ce qui peut entra\u00eener des situations dangereuses. Les syst\u00e8mes de fixation des rails d&rsquo;edilon)(sedra sont con\u00e7us pour une isolation optimale des<a class=\"excerpt-read-more\" href=\"https:\/\/www.edilonsedra.com\/fr\/discover\/isolation-electrique\/\" title=\"En savoir plusIsolation \u00e9lectrique\">&#8230; En savoir plus \u00bb<\/a><\/p>\n","protected":false},"author":1,"featured_media":4255,"menu_order":0,"template":"","class_list":["post-4474","discover","type-discover","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Isolation \u00e9lectrique - edilon)(sedra<\/title>\n<meta name=\"description\" content=\"Les courants vagabonds sont une cons\u00e9quence n\u00e9faste des syst\u00e8mes ferroviaires \u00e9lectrifi\u00e9s, qui provoquent ou acc\u00e9l\u00e8rent la corrosion \u00e9lectrolytique des rails et des structures m\u00e9talliques environnantes, ce qui peut entra\u00eener des situations dangereuses.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.edilonsedra.com\/fr\/discover\/isolation-electrique\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Isolation \u00e9lectrique - edilon)(sedra\" \/>\n<meta property=\"og:description\" content=\"Les courants vagabonds sont une cons\u00e9quence n\u00e9faste des syst\u00e8mes ferroviaires \u00e9lectrifi\u00e9s, qui provoquent ou acc\u00e9l\u00e8rent la corrosion \u00e9lectrolytique des rails et des structures m\u00e9talliques environnantes, ce qui peut entra\u00eener des situations dangereuses.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.edilonsedra.com\/fr\/discover\/isolation-electrique\/\" \/>\n<meta property=\"og:site_name\" content=\"edilon)(sedra\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-05T08:36:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.edilonsedra.com\/wp-content\/uploads\/2022\/08\/Corkelast-ERS-Hardbruecke-Zurich-e1682325308887-1024x611.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"611\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.edilonsedra.com\\\/fr\\\/discover\\\/isolation-electrique\\\/\",\"url\":\"https:\\\/\\\/www.edilonsedra.com\\\/fr\\\/discover\\\/isolation-electrique\\\/\",\"name\":\"Isolation \u00e9lectrique - edilon)(sedra\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.edilonsedra.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.edilonsedra.com\\\/fr\\\/discover\\\/isolation-electrique\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.edilonsedra.com\\\/fr\\\/discover\\\/isolation-electrique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.edilonsedra.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Corkelast-ERS-Hardbruecke-Zurich-e1682325308887.jpg\",\"datePublished\":\"2022-08-15T14:38:39+00:00\",\"dateModified\":\"2023-10-05T08:36:05+00:00\",\"description\":\"Les courants vagabonds sont une cons\u00e9quence n\u00e9faste des syst\u00e8mes ferroviaires \u00e9lectrifi\u00e9s, qui provoquent ou acc\u00e9l\u00e8rent la corrosion \u00e9lectrolytique des rails et des structures m\u00e9talliques environnantes, ce qui peut entra\u00eener des situations dangereuses.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.edilonsedra.com\\\/fr\\\/discover\\\/isolation-electrique\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.edilonsedra.com\\\/fr\\\/discover\\\/isolation-electrique\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.edilonsedra.com\\\/fr\\\/discover\\\/isolation-electrique\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.edilonsedra.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Corkelast-ERS-Hardbruecke-Zurich-e1682325308887.jpg\",\"contentUrl\":\"https:\\\/\\\/www.edilonsedra.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Corkelast-ERS-Hardbruecke-Zurich-e1682325308887.jpg\",\"width\":2493,\"height\":1487},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.edilonsedra.com\\\/fr\\\/discover\\\/isolation-electrique\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.edilonsedra.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Isolation \u00e9lectrique\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.edilonsedra.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.edilonsedra.com\\\/fr\\\/\",\"name\":\"edilon)(sedra\",\"description\":\"Always a step ahead in rail systems\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.edilonsedra.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Isolation \u00e9lectrique - edilon)(sedra","description":"Les courants vagabonds sont une cons\u00e9quence n\u00e9faste des syst\u00e8mes ferroviaires \u00e9lectrifi\u00e9s, qui provoquent ou acc\u00e9l\u00e8rent la corrosion \u00e9lectrolytique des rails et des structures m\u00e9talliques environnantes, ce qui peut entra\u00eener des situations dangereuses.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.edilonsedra.com\/fr\/discover\/isolation-electrique\/","og_locale":"fr_FR","og_type":"article","og_title":"Isolation \u00e9lectrique - edilon)(sedra","og_description":"Les courants vagabonds sont une cons\u00e9quence n\u00e9faste des syst\u00e8mes ferroviaires \u00e9lectrifi\u00e9s, qui provoquent ou acc\u00e9l\u00e8rent la corrosion \u00e9lectrolytique des rails et des structures m\u00e9talliques environnantes, ce qui peut entra\u00eener des situations dangereuses.","og_url":"https:\/\/www.edilonsedra.com\/fr\/discover\/isolation-electrique\/","og_site_name":"edilon)(sedra","article_modified_time":"2023-10-05T08:36:05+00:00","og_image":[{"width":1024,"height":611,"url":"https:\/\/www.edilonsedra.com\/wp-content\/uploads\/2022\/08\/Corkelast-ERS-Hardbruecke-Zurich-e1682325308887-1024x611.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.edilonsedra.com\/fr\/discover\/isolation-electrique\/","url":"https:\/\/www.edilonsedra.com\/fr\/discover\/isolation-electrique\/","name":"Isolation \u00e9lectrique - edilon)(sedra","isPartOf":{"@id":"https:\/\/www.edilonsedra.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.edilonsedra.com\/fr\/discover\/isolation-electrique\/#primaryimage"},"image":{"@id":"https:\/\/www.edilonsedra.com\/fr\/discover\/isolation-electrique\/#primaryimage"},"thumbnailUrl":"https:\/\/www.edilonsedra.com\/wp-content\/uploads\/2022\/08\/Corkelast-ERS-Hardbruecke-Zurich-e1682325308887.jpg","datePublished":"2022-08-15T14:38:39+00:00","dateModified":"2023-10-05T08:36:05+00:00","description":"Les courants vagabonds sont une cons\u00e9quence n\u00e9faste des syst\u00e8mes ferroviaires \u00e9lectrifi\u00e9s, qui provoquent ou acc\u00e9l\u00e8rent la corrosion \u00e9lectrolytique des rails et des structures m\u00e9talliques environnantes, ce qui peut entra\u00eener des situations dangereuses.","breadcrumb":{"@id":"https:\/\/www.edilonsedra.com\/fr\/discover\/isolation-electrique\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.edilonsedra.com\/fr\/discover\/isolation-electrique\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.edilonsedra.com\/fr\/discover\/isolation-electrique\/#primaryimage","url":"https:\/\/www.edilonsedra.com\/wp-content\/uploads\/2022\/08\/Corkelast-ERS-Hardbruecke-Zurich-e1682325308887.jpg","contentUrl":"https:\/\/www.edilonsedra.com\/wp-content\/uploads\/2022\/08\/Corkelast-ERS-Hardbruecke-Zurich-e1682325308887.jpg","width":2493,"height":1487},{"@type":"BreadcrumbList","@id":"https:\/\/www.edilonsedra.com\/fr\/discover\/isolation-electrique\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.edilonsedra.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Isolation \u00e9lectrique"}]},{"@type":"WebSite","@id":"https:\/\/www.edilonsedra.com\/fr\/#website","url":"https:\/\/www.edilonsedra.com\/fr\/","name":"edilon)(sedra","description":"Always a step ahead in rail systems","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.edilonsedra.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.edilonsedra.com\/fr\/wp-json\/wp\/v2\/discover\/4474","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.edilonsedra.com\/fr\/wp-json\/wp\/v2\/discover"}],"about":[{"href":"https:\/\/www.edilonsedra.com\/fr\/wp-json\/wp\/v2\/types\/discover"}],"author":[{"embeddable":true,"href":"https:\/\/www.edilonsedra.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":3,"href":"https:\/\/www.edilonsedra.com\/fr\/wp-json\/wp\/v2\/discover\/4474\/revisions"}],"predecessor-version":[{"id":5987,"href":"https:\/\/www.edilonsedra.com\/fr\/wp-json\/wp\/v2\/discover\/4474\/revisions\/5987"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.edilonsedra.com\/fr\/wp-json\/wp\/v2\/media\/4255"}],"wp:attachment":[{"href":"https:\/\/www.edilonsedra.com\/fr\/wp-json\/wp\/v2\/media?parent=4474"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}